{"id":145,"date":"2023-11-23T09:00:19","date_gmt":"2023-11-23T08:00:19","guid":{"rendered":"https:\/\/mathriders.pl\/lublin\/?page_id=145"},"modified":"2023-12-02T13:40:34","modified_gmt":"2023-12-02T12:40:34","slug":"oferta","status":"publish","type":"page","link":"https:\/\/mathriders.pl\/miasto-lublin\/oferta\/","title":{"rendered":"Oferta"},"content":{"rendered":"<style>.kb-row-layout-id145_63f3b1-27 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id145_63f3b1-27 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id145_63f3b1-27 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1290px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:var(--global-kb-spacing-5xl, 10rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id145_63f3b1-27 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id145_63f3b1-27 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id145_63f3b1-27 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id145_63f3b1-27 alignfull wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column145_ac6c85-7b > .kt-inside-inner-col,.kadence-column145_ac6c85-7b > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column145_ac6c85-7b > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column145_ac6c85-7b > .kt-inside-inner-col{flex-direction:column;}.kadence-column145_ac6c85-7b > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column145_ac6c85-7b > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column145_ac6c85-7b{position:relative;}@media all and (max-width: 1024px){.kadence-column145_ac6c85-7b > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column145_ac6c85-7b > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column145_ac6c85-7b\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading145_ea8160-b9, .wp-block-kadence-advancedheading.kt-adv-heading145_ea8160-b9[data-kb-block=\"kb-adv-heading145_ea8160-b9\"]{padding-bottom:0px;margin-bottom:0px;text-align:center;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading145_ea8160-b9 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading145_ea8160-b9[data-kb-block=\"kb-adv-heading145_ea8160-b9\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading145_ea8160-b9 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading145_ea8160-b9[data-kb-block=\"kb-adv-heading145_ea8160-b9\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h1 class=\"kt-adv-heading145_ea8160-b9 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading145_ea8160-b9\">Oferta<\/h1>\n\n\n\n<p class=\"has-text-align-center\">Lublin<\/p>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-id130_523adf-b9 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id130_523adf-b9 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id130_523adf-b9 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1290px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:var(--global-kb-spacing-lg, 3rem);padding-bottom:var(--global-kb-spacing-lg, 3rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id130_523adf-b9 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id130_523adf-b9 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id130_523adf-b9 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id130_523adf-b9 alignfull wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column130_bc53e5-13 > .kt-inside-inner-col,.kadence-column130_bc53e5-13 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column130_bc53e5-13 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column130_bc53e5-13 > .kt-inside-inner-col{flex-direction:column;}.kadence-column130_bc53e5-13 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column130_bc53e5-13 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column130_bc53e5-13{position:relative;}@media all and (max-width: 1024px){.kadence-column130_bc53e5-13 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column130_bc53e5-13 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column130_bc53e5-13\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading130_b4065c-fc, .wp-block-kadence-advancedheading.kt-adv-heading130_b4065c-fc[data-kb-block=\"kb-adv-heading130_b4065c-fc\"]{margin-bottom:var(--global-kb-spacing-xxs, 0.5rem);text-align:center;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading130_b4065c-fc mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading130_b4065c-fc[data-kb-block=\"kb-adv-heading130_b4065c-fc\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading130_b4065c-fc img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading130_b4065c-fc[data-kb-block=\"kb-adv-heading130_b4065c-fc\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h2 class=\"kt-adv-heading130_b4065c-fc wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading130_b4065c-fc\">Nasze kursy<\/h2>\n\n\n<style>.kb-row-layout-id130_0fe359-69 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id130_0fe359-69 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id130_0fe359-69 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1290px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);}.kb-row-layout-id130_0fe359-69 > .kt-row-column-wrap > div:not(.added-for-specificity){grid-column:initial;}.kb-row-layout-id130_0fe359-69 > .kt-row-column-wrap{grid-template-columns:repeat(3, minmax(0, 1fr));}.kb-row-layout-id130_0fe359-69 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id130_0fe359-69 > .kt-row-column-wrap > div:not(.added-for-specificity){grid-column:initial;}}@media all and (max-width: 1024px){.kb-row-layout-id130_0fe359-69 > .kt-row-column-wrap{grid-template-columns:repeat(3, minmax(0, 1fr));}}@media all and (max-width: 767px){.kb-row-layout-id130_0fe359-69 > .kt-row-column-wrap > div:not(.added-for-specificity){grid-column:initial;}.kb-row-layout-id130_0fe359-69 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id130_0fe359-69 alignfull wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-3-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column130_a8aa09-da > .kt-inside-inner-col,.kadence-column130_a8aa09-da > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column130_a8aa09-da > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column130_a8aa09-da > .kt-inside-inner-col{flex-direction:column;}.kadence-column130_a8aa09-da > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column130_a8aa09-da > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column130_a8aa09-da{position:relative;}@media all and (max-width: 1024px){.kadence-column130_a8aa09-da > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column130_a8aa09-da > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column130_a8aa09-da\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-image.kb-image130_8a7ae8-c9:not(.kb-specificity-added):not(.kb-extra-specificity-added){margin-bottom:var(--global-kb-spacing-xxs, 0.5rem);}.kb-image130_8a7ae8-c9:not(.kb-image-is-ratio-size) .kb-img, .kb-image130_8a7ae8-c9.kb-image-is-ratio-size{padding-bottom:0px;}.kb-image130_8a7ae8-c9 .kb-image-has-overlay:after{opacity:0.3;}<\/style>\n<div class=\"wp-block-kadence-image kb-image130_8a7ae8-c9\"><figure class=\"aligncenter size-full\"><a href=\"https:\/\/mathriders.pl\/miasto-lublin\/kurs-starter-2-4-lat\/\" class=\"kb-advanced-image-link\"><img loading=\"lazy\" decoding=\"async\" width=\"350\" height=\"350\" src=\"https:\/\/mathriders.pl\/miasto-lublin\/wp-content\/uploads\/sites\/8\/2023\/11\/2d4f84a10baf91247898e5b387af5540.webp\" alt=\"\" class=\"kb-img wp-image-34\" srcset=\"https:\/\/mathriders.pl\/miasto-lublin\/wp-content\/uploads\/sites\/8\/2023\/11\/2d4f84a10baf91247898e5b387af5540.webp 350w, https:\/\/mathriders.pl\/miasto-lublin\/wp-content\/uploads\/sites\/8\/2023\/11\/2d4f84a10baf91247898e5b387af5540-300x300.webp 300w, https:\/\/mathriders.pl\/miasto-lublin\/wp-content\/uploads\/sites\/8\/2023\/11\/2d4f84a10baf91247898e5b387af5540-150x150.webp 150w\" sizes=\"auto, (max-width: 350px) 100vw, 350px\" \/><\/a><\/figure><\/div>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading130_2cd289-4b, .wp-block-kadence-advancedheading.kt-adv-heading130_2cd289-4b[data-kb-block=\"kb-adv-heading130_2cd289-4b\"]{text-align:center;font-size:23px;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading130_2cd289-4b mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading130_2cd289-4b[data-kb-block=\"kb-adv-heading130_2cd289-4b\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading130_2cd289-4b img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading130_2cd289-4b[data-kb-block=\"kb-adv-heading130_2cd289-4b\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<p class=\"kt-adv-heading130_2cd289-4b wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading130_2cd289-4b\"><strong>2-4 lata<\/strong><br>Starter<\/p>\n\n\n\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-16018d1d wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link has-theme-palette-8-color has-theme-palette-2-background-color has-text-color has-background wp-element-button\" href=\"https:\/\/mathriders.pl\/miasto-lublin\/kurs-starter-2-4-lat\/\">Wybierz<\/a><\/div>\n<\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column130_2c1e0d-08 > .kt-inside-inner-col,.kadence-column130_2c1e0d-08 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column130_2c1e0d-08 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column130_2c1e0d-08 > .kt-inside-inner-col{flex-direction:column;}.kadence-column130_2c1e0d-08 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column130_2c1e0d-08 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column130_2c1e0d-08{position:relative;}@media all and (max-width: 1024px){.kadence-column130_2c1e0d-08 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column130_2c1e0d-08 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column130_2c1e0d-08\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-image.kb-image130_751f09-bb:not(.kb-specificity-added):not(.kb-extra-specificity-added){margin-bottom:var(--global-kb-spacing-xxs, 0.5rem);}.kb-image130_751f09-bb:not(.kb-image-is-ratio-size) .kb-img, .kb-image130_751f09-bb.kb-image-is-ratio-size{padding-bottom:0px;}.kb-image130_751f09-bb .kb-image-has-overlay:after{opacity:0.3;}<\/style>\n<div class=\"wp-block-kadence-image kb-image130_751f09-bb\"><figure class=\"aligncenter size-full\"><a href=\"https:\/\/mathriders.pl\/miasto-lublin\/kurs-junior-5-11-lat\/\" class=\"kb-advanced-image-link\"><img loading=\"lazy\" decoding=\"async\" width=\"350\" height=\"350\" src=\"https:\/\/mathriders.pl\/miasto-lublin\/wp-content\/uploads\/sites\/8\/2023\/11\/7099674fc5e682e919f157a48a147180.webp\" alt=\"\" class=\"kb-img wp-image-35\" srcset=\"https:\/\/mathriders.pl\/miasto-lublin\/wp-content\/uploads\/sites\/8\/2023\/11\/7099674fc5e682e919f157a48a147180.webp 350w, https:\/\/mathriders.pl\/miasto-lublin\/wp-content\/uploads\/sites\/8\/2023\/11\/7099674fc5e682e919f157a48a147180-300x300.webp 300w, https:\/\/mathriders.pl\/miasto-lublin\/wp-content\/uploads\/sites\/8\/2023\/11\/7099674fc5e682e919f157a48a147180-150x150.webp 150w\" sizes=\"auto, (max-width: 350px) 100vw, 350px\" \/><\/a><\/figure><\/div>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading130_904bf8-80, .wp-block-kadence-advancedheading.kt-adv-heading130_904bf8-80[data-kb-block=\"kb-adv-heading130_904bf8-80\"]{text-align:center;font-size:23px;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading130_904bf8-80 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading130_904bf8-80[data-kb-block=\"kb-adv-heading130_904bf8-80\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading130_904bf8-80 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading130_904bf8-80[data-kb-block=\"kb-adv-heading130_904bf8-80\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<p class=\"kt-adv-heading130_904bf8-80 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading130_904bf8-80\"><strong>5-11 lat<\/strong><br>Junior<\/p>\n\n\n\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-16018d1d wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link has-theme-palette-8-color has-theme-palette-2-background-color has-text-color has-background wp-element-button\" href=\"https:\/\/mathriders.pl\/miasto-lublin\/kurs-junior-5-11-lat\/\">Wybierz<\/a><\/div>\n<\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column130_421dd4-ae > .kt-inside-inner-col,.kadence-column130_421dd4-ae > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column130_421dd4-ae > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column130_421dd4-ae > .kt-inside-inner-col{flex-direction:column;}.kadence-column130_421dd4-ae > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column130_421dd4-ae > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column130_421dd4-ae{position:relative;}@media all and (max-width: 1024px){.kadence-column130_421dd4-ae > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column130_421dd4-ae > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column130_421dd4-ae\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-image.kb-image130_f17a62-7a:not(.kb-specificity-added):not(.kb-extra-specificity-added){margin-bottom:var(--global-kb-spacing-xxs, 0.5rem);}.kb-image130_f17a62-7a:not(.kb-image-is-ratio-size) .kb-img, .kb-image130_f17a62-7a.kb-image-is-ratio-size{padding-bottom:0px;}.kb-image130_f17a62-7a .kb-image-has-overlay:after{opacity:0.3;}<\/style>\n<div class=\"wp-block-kadence-image kb-image130_f17a62-7a\"><figure class=\"aligncenter size-full\"><a href=\"https:\/\/mathriders.pl\/miasto-lublin\/kurs-advanced-11-19-lat\/\" class=\"kb-advanced-image-link\"><img loading=\"lazy\" decoding=\"async\" width=\"350\" height=\"350\" src=\"https:\/\/mathriders.pl\/miasto-lublin\/wp-content\/uploads\/sites\/8\/2023\/11\/6f619cca0b7ca21f6de914da91a4c4c8.webp\" alt=\"\" class=\"kb-img wp-image-36\" srcset=\"https:\/\/mathriders.pl\/miasto-lublin\/wp-content\/uploads\/sites\/8\/2023\/11\/6f619cca0b7ca21f6de914da91a4c4c8.webp 350w, https:\/\/mathriders.pl\/miasto-lublin\/wp-content\/uploads\/sites\/8\/2023\/11\/6f619cca0b7ca21f6de914da91a4c4c8-300x300.webp 300w, https:\/\/mathriders.pl\/miasto-lublin\/wp-content\/uploads\/sites\/8\/2023\/11\/6f619cca0b7ca21f6de914da91a4c4c8-150x150.webp 150w\" sizes=\"auto, (max-width: 350px) 100vw, 350px\" \/><\/a><\/figure><\/div>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading130_546e73-15, .wp-block-kadence-advancedheading.kt-adv-heading130_546e73-15[data-kb-block=\"kb-adv-heading130_546e73-15\"]{text-align:center;font-size:23px;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading130_546e73-15 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading130_546e73-15[data-kb-block=\"kb-adv-heading130_546e73-15\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading130_546e73-15 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading130_546e73-15[data-kb-block=\"kb-adv-heading130_546e73-15\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<p class=\"kt-adv-heading130_546e73-15 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading130_546e73-15\"><strong>11-19 lat<\/strong><br>Advanced<\/p>\n\n\n\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-16018d1d wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link has-theme-palette-8-color has-theme-palette-2-background-color has-text-color has-background wp-element-button\" href=\"https:\/\/mathriders.pl\/miasto-lublin\/kurs-advanced-11-19-lat\/\">Wybierz<\/a><\/div>\n<\/div>\n<\/div><\/div>\n\n<\/div><\/div><\/div><\/div>\n\n<\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Oferta Lublin<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","footnotes":""},"class_list":["post-145","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Oferta - Lublin<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mathriders.pl\/miasto-lublin\/oferta\/\" \/>\n<meta property=\"og:locale\" content=\"pl_PL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Oferta - Lublin\" \/>\n<meta property=\"og:description\" content=\"Oferta Lublin\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mathriders.pl\/miasto-lublin\/oferta\/\" \/>\n<meta property=\"og:site_name\" content=\"Lublin\" \/>\n<meta property=\"article:modified_time\" content=\"2023-12-02T12:40:34+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mathriders.pl\\\/miasto-lublin\\\/oferta\\\/\",\"url\":\"https:\\\/\\\/mathriders.pl\\\/miasto-lublin\\\/oferta\\\/\",\"name\":\"Oferta - Lublin\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mathriders.pl\\\/miasto-lublin\\\/#website\"},\"datePublished\":\"2023-11-23T08:00:19+00:00\",\"dateModified\":\"2023-12-02T12:40:34+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mathriders.pl\\\/miasto-lublin\\\/oferta\\\/#breadcrumb\"},\"inLanguage\":\"pl-PL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/mathriders.pl\\\/miasto-lublin\\\/oferta\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mathriders.pl\\\/miasto-lublin\\\/oferta\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Strona g\u0142\u00f3wna\",\"item\":\"https:\\\/\\\/mathriders.pl\\\/miasto-lublin\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Oferta\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mathriders.pl\\\/miasto-lublin\\\/#website\",\"url\":\"https:\\\/\\\/mathriders.pl\\\/miasto-lublin\\\/\",\"name\":\"Lublin\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/mathriders.pl\\\/miasto-lublin\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mathriders.pl\\\/miasto-lublin\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pl-PL\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/mathriders.pl\\\/miasto-lublin\\\/#organization\",\"name\":\"Lublin\",\"url\":\"https:\\\/\\\/mathriders.pl\\\/miasto-lublin\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pl-PL\",\"@id\":\"https:\\\/\\\/mathriders.pl\\\/miasto-lublin\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/mathriders.pl\\\/miasto-lublin\\\/wp-content\\\/uploads\\\/sites\\\/8\\\/2023\\\/11\\\/logo.webp\",\"contentUrl\":\"https:\\\/\\\/mathriders.pl\\\/miasto-lublin\\\/wp-content\\\/uploads\\\/sites\\\/8\\\/2023\\\/11\\\/logo.webp\",\"width\":157,\"height\":82,\"caption\":\"Lublin\"},\"image\":{\"@id\":\"https:\\\/\\\/mathriders.pl\\\/miasto-lublin\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Oferta - Lublin","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mathriders.pl\/miasto-lublin\/oferta\/","og_locale":"pl_PL","og_type":"article","og_title":"Oferta - Lublin","og_description":"Oferta Lublin","og_url":"https:\/\/mathriders.pl\/miasto-lublin\/oferta\/","og_site_name":"Lublin","article_modified_time":"2023-12-02T12:40:34+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/mathriders.pl\/miasto-lublin\/oferta\/","url":"https:\/\/mathriders.pl\/miasto-lublin\/oferta\/","name":"Oferta - Lublin","isPartOf":{"@id":"https:\/\/mathriders.pl\/miasto-lublin\/#website"},"datePublished":"2023-11-23T08:00:19+00:00","dateModified":"2023-12-02T12:40:34+00:00","breadcrumb":{"@id":"https:\/\/mathriders.pl\/miasto-lublin\/oferta\/#breadcrumb"},"inLanguage":"pl-PL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mathriders.pl\/miasto-lublin\/oferta\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/mathriders.pl\/miasto-lublin\/oferta\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Strona g\u0142\u00f3wna","item":"https:\/\/mathriders.pl\/miasto-lublin\/"},{"@type":"ListItem","position":2,"name":"Oferta"}]},{"@type":"WebSite","@id":"https:\/\/mathriders.pl\/miasto-lublin\/#website","url":"https:\/\/mathriders.pl\/miasto-lublin\/","name":"Lublin","description":"","publisher":{"@id":"https:\/\/mathriders.pl\/miasto-lublin\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mathriders.pl\/miasto-lublin\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pl-PL"},{"@type":"Organization","@id":"https:\/\/mathriders.pl\/miasto-lublin\/#organization","name":"Lublin","url":"https:\/\/mathriders.pl\/miasto-lublin\/","logo":{"@type":"ImageObject","inLanguage":"pl-PL","@id":"https:\/\/mathriders.pl\/miasto-lublin\/#\/schema\/logo\/image\/","url":"https:\/\/mathriders.pl\/miasto-lublin\/wp-content\/uploads\/sites\/8\/2023\/11\/logo.webp","contentUrl":"https:\/\/mathriders.pl\/miasto-lublin\/wp-content\/uploads\/sites\/8\/2023\/11\/logo.webp","width":157,"height":82,"caption":"Lublin"},"image":{"@id":"https:\/\/mathriders.pl\/miasto-lublin\/#\/schema\/logo\/image\/"}}]}},"taxonomy_info":[],"featured_image_src_large":false,"author_info":{"display_name":"gootek","author_link":"https:\/\/mathriders.pl\/miasto-lublin\/aktualnosci\/author\/gootek\/"},"comment_info":0,"_links":{"self":[{"href":"https:\/\/mathriders.pl\/miasto-lublin\/wp-json\/wp\/v2\/pages\/145","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mathriders.pl\/miasto-lublin\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/mathriders.pl\/miasto-lublin\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/mathriders.pl\/miasto-lublin\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/mathriders.pl\/miasto-lublin\/wp-json\/wp\/v2\/comments?post=145"}],"version-history":[{"count":5,"href":"https:\/\/mathriders.pl\/miasto-lublin\/wp-json\/wp\/v2\/pages\/145\/revisions"}],"predecessor-version":[{"id":354,"href":"https:\/\/mathriders.pl\/miasto-lublin\/wp-json\/wp\/v2\/pages\/145\/revisions\/354"}],"wp:attachment":[{"href":"https:\/\/mathriders.pl\/miasto-lublin\/wp-json\/wp\/v2\/media?parent=145"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}